{"id":1792,"date":"2022-03-17T19:30:22","date_gmt":"2022-03-17T11:30:22","guid":{"rendered":"https:\/\/blog.lansitec.com\/?p=537"},"modified":"2025-08-26T03:14:52","modified_gmt":"2025-08-26T10:14:52","slug":"features-of-container-tracker-and-uses-cases-introduction","status":"publish","type":"post","link":"https:\/\/www.lansitec.com\/de\/blogs\/einfuhrung-in-die-funktionen-und-anwendungsfalle-des-container-trackers\/","title":{"rendered":"Funktionen von Container Tracker und Anwendungsf\u00e4lle Einf\u00fchrung"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"1792\" class=\"elementor elementor-1792\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-61156e38 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"61156e38\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4900325a\" data-id=\"4900325a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-85de394 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"85de394\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img fetchpriority=\"high\" decoding=\"async\" width=\"620\" height=\"620\" src=\"https:\/\/www.lansitec.com\/wp-content\/uploads\/2023\/05\/1024-LoRaWAN-Container-Tracker.png\" class=\"attachment-neve-blog size-neve-blog wp-image-7898\" alt=\"LoRaWAN Container-Tracker\" title=\"\"><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-title\">Container-Tracker<\/p><p class=\"elementor-image-box-description\">Der Lansitec Container Tracker basiert auf GNSS-, Bluetooth- und LoRaWAN\/NB-IoT\/LTE-M-Technologie f\u00fcr die Ortung im Innen- und Au\u00dfenbereich. Er verf\u00fcgt \u00fcber eine extrem lange Standby-Zeit und ein IP68-Geh\u00e4use, wodurch er sich perfekt f\u00fcr die Anlagenortung eignet.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac5d9d8 elementor-mobile-align-center elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"ac5d9d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.lansitec.com\/de\/produkte\/lorawan-container-tracker\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ger\u00e4tespezifikationen &gt;<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6564532a elementor-widget elementor-widget-text-editor\" data-id=\"6564532a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><\/p>\n<p><strong>Pr\u00e4zises Outdoor- und Indoor-Tracking:<\/strong> <br \/>Der vielseitige Tracker verf\u00fcgt \u00fcber integriertes Bluetooth f\u00fcr die Ortung im Innenbereich und GNSS (GPS, Beidou, Glonass) f\u00fcr die Ortung im Au\u00dfenbereich. Die UUID des Ger\u00e4ts kann ge\u00e4ndert werden, um zu verhindern, dass andere Ihre beeinflussen. Sie k\u00f6nnen das GNSS aktivieren\/deaktivieren, um Strom zu sparen, wenn Sie nur die Ortung von Containern im Innenbereich ben\u00f6tigen.<\/p>\n<p><strong>Bluetooth-Tracking:<\/strong> <br \/>Ein Benutzer kann ein l\u00e4ngeres GNSS-Berichtsintervall einstellen, um Energie zu sparen. W\u00e4hrend des Berichtsintervalls kann sich das Objekt jedoch mehrmals im Lager aufgehalten und wieder verlassen haben, was zu einem Verlust der Positionsinformationen f\u00fchrt. Kontaktieren Sie uns, um zu erfahren, wie Sie das Intervall in verschiedene Abschnitte unterteilen k\u00f6nnen. <a href=\"https:\/\/www.lansitec.com\/th\/blogs\/\u0e04\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\/\">Bluetooth-Empfang<\/a> Stationen zur kontinuierlichen \u00dcberwachung Ihrer Anlagen.<\/p>\n<p><strong>Flexible Standortwarnungen und Heartbeat-Berichtsintervalle:<\/strong> <br \/>Senden Sie einen Befehl, um das Intervall f\u00fcr die Standortverfolgung des Verm\u00f6genswerts anzupassen.<\/p>\n<p><strong>Dauer der Bewegung:<\/strong> Die Dauer, f\u00fcr die sich der Tracker zwischen festgelegten Herzschl\u00e4gen bewegt hat. Die Funktion hilft zu beurteilen, wie lange das Ger\u00e4t t\u00e4glich arbeitet.<\/p>\n<p><strong>Unabh\u00e4ngiger Ansatz:<br \/><\/strong> Der Tracker sendet bei Bewegung gelegentlich Positionsaktualisierungen, w\u00e4hrend er statisch ist, werden keine Positionsinformationen weitergegeben. Dies verl\u00e4ngert die Batterielebensdauer und sorgt f\u00fcr ein Gleichgewicht zwischen Wartung und Nutzung.<\/p>\n<p><strong>Bewegungsintervall:<\/strong> <br \/>Der Tracker zeichnet die Zeit auf, die er im letzten gemeldeten Zyklus zur\u00fcckgelegt hat. Er hilft dem Benutzer, die Dauer zu berechnen, die seine Maschine gearbeitet hat.<\/p>\n<p><strong>Maschinen- und Fahrzeugmanagement: <br \/><\/strong> Der Tracker meldet nur nahe Gegebenheiten <a href=\"https:\/\/www.lansitec.com\/th\/\u0e1a\u0e35\u0e04\u0e2d\u0e19\u0e1a\u0e25\u0e39\u0e17\u0e39\u0e18-2\/\">Bluetooth-Beacons<\/a> oder Tag-Informationen. Wenn mehrere Objekte mit einem Bluetooth-Tag versehen sind, k\u00f6nnen Sie feststellen, wie viele sich in unmittelbarer N\u00e4he befinden.<\/p>\n<p><strong>Temperatur: <br \/><\/strong> Der Tracker zeichnet die Temperatur im Inneren auf und gibt sie an. Obwohl es sich nicht um einen professionellen Temperatursensor handelt, gibt er einen Eindruck von der allgemeinen Umgebungstemperatur.<\/p>\n<p><strong>Netzschalter: <br \/><\/strong> Sie k\u00f6nnen den Schalter aktivieren\/deaktivieren, um zu verhindern, dass Leute ihn ausschalten.<\/p>\n<p><strong>Schadenserkennung: <br \/><\/strong> Der Tracker benachrichtigt den Server sofort, wenn er vom Magneten getrennt wird. Wenn also jemand vorhat, den Tracker zu besch\u00e4digen oder zu stehlen, wissen Sie auf keinen Fall, dass er nicht mehr funktioniert.<\/p>\n<p><strong>Cache-Standortbericht offline: <br \/><\/strong> Jedes drahtlose Ger\u00e4t ist manchmal offline, so auch ein LoRA-Tracker. Was uns jedoch besser macht, ist unsere <a href=\"https:\/\/www.lansitec.com\/de\/products\/container-tracker\/\">Container-Tracker<\/a> speichert die letzten 40 Standortmeldungen und sendet sie an Ihren Server, sobald sie online sind.<\/p>\n<p><strong>Akkulaufzeit: <br \/><\/strong> Sein 8000-mAh-Akku kann Ihnen rund 60.000 GNSS-Koordinaten senden. Die Lebensdauer des Akkus betr\u00e4gt mehr als 6 Jahre, wobei jede Stunde ein GNSS-Bericht gesendet wird.<\/p>\n<p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Der Lansitec Container Tracker basiert auf GNSS-, Bluetooth- und LoRaWAN\/NB-IoT\/LTE-M-Technologie f\u00fcr die Ortung im Innen- und Au\u00dfenbereich. Dank seiner extrem langen Standby-Zeit und des IP68-Geh\u00e4uses eignet er sich ideal f\u00fcr die Objektverfolgung. Ger\u00e4tespezifikationen &gt; Pr\u00e4zise Ortung im Innen- und Au\u00dfenbereich: Der vielseitige Tracker verf\u00fcgt \u00fcber integriertes Bluetooth f\u00fcr die Ortung in Innenr\u00e4umen und GNSS\u2026&nbsp;<a href=\"https:\/\/www.lansitec.com\/de\/blogs\/einfuhrung-in-die-funktionen-und-anwendungsfalle-des-container-trackers\/\" rel=\"bookmark\">Weiterlesen \u00bb<span class=\"screen-reader-text\">Funktionen von Container Tracker und Anwendungsf\u00e4lle Einf\u00fchrung<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":16531,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[104],"tags":[91,60,61,98,97,62],"class_list":["post-1792","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-product-review","tag-battery-powered-gps-trackers-with-5-years-battery-life","tag-container-tracker","tag-gps-industrial-tracker","tag-gps-shipping-tracker","tag-gps-trailer-trackers","tag-industrial-tracker"],"_links":{"self":[{"href":"https:\/\/www.lansitec.com\/de\/wp-json\/wp\/v2\/posts\/1792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lansitec.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lansitec.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lansitec.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lansitec.com\/de\/wp-json\/wp\/v2\/comments?post=1792"}],"version-history":[{"count":0,"href":"https:\/\/www.lansitec.com\/de\/wp-json\/wp\/v2\/posts\/1792\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lansitec.com\/de\/wp-json\/wp\/v2\/media\/16531"}],"wp:attachment":[{"href":"https:\/\/www.lansitec.com\/de\/wp-json\/wp\/v2\/media?parent=1792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lansitec.com\/de\/wp-json\/wp\/v2\/categories?post=1792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lansitec.com\/de\/wp-json\/wp\/v2\/tags?post=1792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}